{"id":360,"date":"2021-10-27T09:26:28","date_gmt":"2021-10-27T09:26:28","guid":{"rendered":"https:\/\/volteco.local\/product\/aquascud-line\/"},"modified":"2026-04-21T08:07:09","modified_gmt":"2026-04-21T08:07:09","slug":"aquascud-line","status":"publish","type":"product","link":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line","title":{"rendered":"AQUASCUD LINE"},"content":{"rendered":"<p>Profilo gocciolatoio drenante in alluminio verniciato per la finitura e protezione perimetrale di terrazze e balconi, atto a favorire un corretto deflusso delle acque.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profilo drenante con doppio gocciolatoio<\/p>\n","protected":false},"featured_media":50851,"template":"","scope":[1117],"problem":[922,748,921,1133,1134,1122,1132],"product_category":[1111,1603],"class_list":["post-360","product","type-product","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-terrazzi-e-balconi","problem-infiltrazioni-soluzioni","problem-fessurazioni-soluzioni","problem-deterioramento-soluzioni","problem-parapetti-e-frontalini-degradati","problem-infiltrazioni-dal-tetto-piano","problem-infiltrazioni-dacqua","problem-efflorescenze-su-piastrella","product_category-impermeabilizzanti","product_category-profili-gocciolatoi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aquascud Line profilo drenante con doppio gocciolatoio | Volteco<\/title>\n<meta name=\"description\" content=\"Scopri tutti i prodotti per l&#039;impermeabilizzazione degli edifici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/volteco.com\/it\/prodotti\/aquascud-line\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aquascud Line profilo drenante con doppio gocciolatoio | Volteco\" \/>\n<meta property=\"og:description\" content=\"Scopri tutti i prodotti per l&#039;impermeabilizzazione degli edifici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/volteco.com\/it\/prodotti\/aquascud-line\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T08:07:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/volteco.com\/wp-content\/uploads\/2024\/05\/AQUASCUD_LINE_princi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1875\" \/>\n\t<meta property=\"og:image:height\" content=\"1875\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/aquascud-line\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/aquascud-line\",\"name\":\"Aquascud Line profilo drenante con doppio gocciolatoio | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/aquascud-line#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/aquascud-line#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AQUASCUD_LINE_princi.png\",\"datePublished\":\"2021-10-27T09:26:28+00:00\",\"dateModified\":\"2026-04-21T08:07:09+00:00\",\"description\":\"Scopri tutti i prodotti per l'impermeabilizzazione degli edifici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/aquascud-line#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/aquascud-line\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/aquascud-line#primaryimage\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AQUASCUD_LINE_princi.png\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/AQUASCUD_LINE_princi.png\",\"width\":1875,\"height\":1875},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/aquascud-line#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AQUASCUD LINE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aquascud Line profilo drenante con doppio gocciolatoio | Volteco","description":"Scopri tutti i prodotti per l'impermeabilizzazione degli edifici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line","og_locale":"it_IT","og_type":"article","og_title":"Aquascud Line profilo drenante con doppio gocciolatoio | Volteco","og_description":"Scopri tutti i prodotti per l'impermeabilizzazione degli edifici.","og_url":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2026-04-21T08:07:09+00:00","og_image":[{"width":1875,"height":1875,"url":"https:\/\/volteco.com\/wp-content\/uploads\/2024\/05\/AQUASCUD_LINE_princi.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line","url":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line","name":"Aquascud Line profilo drenante con doppio gocciolatoio | Volteco","isPartOf":{"@id":"https:\/\/volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line#primaryimage"},"image":{"@id":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line#primaryimage"},"thumbnailUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2024\/05\/AQUASCUD_LINE_princi.png","datePublished":"2021-10-27T09:26:28+00:00","dateModified":"2026-04-21T08:07:09+00:00","description":"Scopri tutti i prodotti per l'impermeabilizzazione degli edifici.","breadcrumb":{"@id":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/volteco.com\/it\/prodotti\/aquascud-line"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line#primaryimage","url":"https:\/\/volteco.com\/wp-content\/uploads\/2024\/05\/AQUASCUD_LINE_princi.png","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2024\/05\/AQUASCUD_LINE_princi.png","width":1875,"height":1875},{"@type":"BreadcrumbList","@id":"https:\/\/volteco.com\/it\/prodotti\/aquascud-line#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/volteco.com\/it"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/volteco.com\/it\/prodotti"},{"@type":"ListItem","position":3,"name":"AQUASCUD LINE"}]},{"@type":"WebSite","@id":"https:\/\/volteco.com\/it\/#website","url":"https:\/\/volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/product\/360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media\/50851"}],"wp:attachment":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media?parent=360"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/scope?post=360"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/problem?post=360"},{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/product_category?post=360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}