{"id":404,"date":"2021-10-27T09:26:51","date_gmt":"2021-10-27T09:26:51","guid":{"rendered":"https:\/\/volteco.local\/product\/tap-3\/"},"modified":"2026-04-21T08:09:11","modified_gmt":"2026-04-21T08:09:11","slug":"tap-3","status":"publish","type":"product","link":"https:\/\/volteco.com\/it\/prodotti\/tap-3","title":{"rendered":"TAP 3"},"content":{"rendered":"<p>Malta idraulica impermeabile a presa e indurimento rapidi ideale per lavori veloci di impermeabilizzazione localizzati, anche in presenza di acqua in pressione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Malta idraulica impermeabile a presa rapida<\/p>\n","protected":false},"featured_media":58178,"template":"","scope":[1115,1116],"problem":[922,1135,1122,1125,1126],"product_category":[1111,1104],"class_list":["post-404","product","type-product","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-ambienti-interrati","scope-impermeabilizzazione-piscine-e-vasche","problem-infiltrazioni-soluzioni","problem-perdite-dacqua","problem-infiltrazioni-dacqua","problem-infiltrazioni-nei-locali-tecnici","problem-tubi-non-sigillati","product_category-impermeabilizzanti","product_category-malte-impermeabili-malte-rapide"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tap 3 malta impermeabilizzante rapida | Volteco<\/title>\n<meta name=\"description\" content=\"Scopri tutti i prodotti per l&#039;impermeabilizzazione degli edifici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/volteco.com\/it\/prodotti\/tap-3\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tap 3 malta impermeabilizzante rapida | Volteco\" \/>\n<meta property=\"og:description\" content=\"Scopri tutti i prodotti per l&#039;impermeabilizzazione degli edifici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/volteco.com\/it\/prodotti\/tap-3\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-21T08:09:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/volteco.com\/wp-content\/uploads\/2024\/11\/TAP_3_vaso_scat_2024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/tap-3\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/tap-3\",\"name\":\"Tap 3 malta impermeabilizzante rapida | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/tap-3#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/tap-3#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TAP_3_vaso_scat_2024.png\",\"datePublished\":\"2021-10-27T09:26:51+00:00\",\"dateModified\":\"2026-04-21T08:09:11+00:00\",\"description\":\"Scopri tutti i prodotti per l'impermeabilizzazione degli edifici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/tap-3#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/tap-3\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/tap-3#primaryimage\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TAP_3_vaso_scat_2024.png\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TAP_3_vaso_scat_2024.png\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\\\/tap-3#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\\\/prodotti\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TAP 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tap 3 malta impermeabilizzante rapida | Volteco","description":"Scopri tutti i prodotti per l'impermeabilizzazione degli edifici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/volteco.com\/it\/prodotti\/tap-3","og_locale":"it_IT","og_type":"article","og_title":"Tap 3 malta impermeabilizzante rapida | Volteco","og_description":"Scopri tutti i prodotti per l'impermeabilizzazione degli edifici.","og_url":"https:\/\/volteco.com\/it\/prodotti\/tap-3","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2026-04-21T08:09:11+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/volteco.com\/wp-content\/uploads\/2024\/11\/TAP_3_vaso_scat_2024.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/volteco.com\/it\/prodotti\/tap-3","url":"https:\/\/volteco.com\/it\/prodotti\/tap-3","name":"Tap 3 malta impermeabilizzante rapida | Volteco","isPartOf":{"@id":"https:\/\/volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/volteco.com\/it\/prodotti\/tap-3#primaryimage"},"image":{"@id":"https:\/\/volteco.com\/it\/prodotti\/tap-3#primaryimage"},"thumbnailUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2024\/11\/TAP_3_vaso_scat_2024.png","datePublished":"2021-10-27T09:26:51+00:00","dateModified":"2026-04-21T08:09:11+00:00","description":"Scopri tutti i prodotti per l'impermeabilizzazione degli edifici.","breadcrumb":{"@id":"https:\/\/volteco.com\/it\/prodotti\/tap-3#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/volteco.com\/it\/prodotti\/tap-3"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/prodotti\/tap-3#primaryimage","url":"https:\/\/volteco.com\/wp-content\/uploads\/2024\/11\/TAP_3_vaso_scat_2024.png","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2024\/11\/TAP_3_vaso_scat_2024.png","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/volteco.com\/it\/prodotti\/tap-3#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/volteco.com\/it"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/volteco.com\/it\/prodotti"},{"@type":"ListItem","position":3,"name":"TAP 3"}]},{"@type":"WebSite","@id":"https:\/\/volteco.com\/it\/#website","url":"https:\/\/volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/product\/404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media\/58178"}],"wp:attachment":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media?parent=404"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/scope?post=404"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/problem?post=404"},{"taxonomy":"product_category","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/product_category?post=404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}