{"id":64828,"date":"2025-07-17T12:27:58","date_gmt":"2025-07-17T12:27:58","guid":{"rendered":"https:\/\/volteco.com\/?post_type=reference&#038;p=64828"},"modified":"2025-07-17T12:27:58","modified_gmt":"2025-07-17T12:27:58","slug":"impermeabilizzazione-nuovo-complesso-industriale-ispria-va","status":"publish","type":"reference","link":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va","title":{"rendered":"Impermeabilizzazione nuovo complesso industriale &#8211; Ispria &#8211; VA"},"content":{"rendered":"<p>Lavori di impermeabilizzazione nuovo edificio industriale sito a Ispira in provincia di Varese.<\/p>\n","protected":false},"featured_media":64848,"template":"","scope":[1115],"problem":[784,1123,1126],"country":[1197],"building":[33],"class_list":["post-64828","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-ambienti-interrati","problem-ruggine-soluzioni","problem-infiltrazioni-dacqua-di-falda","problem-tubi-non-sigillati","country-lombardia","building-industriale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impermeabilizzazione nuovo complesso industriale - Ispria - VA | Volteco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impermeabilizzazione nuovo complesso industriale - Ispria - VA | Volteco\" \/>\n<meta property=\"og:description\" content=\"Lavori di impermeabilizzazione nuovo edificio industriale sito a Ispira in provincia di Varese.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"og:image\" content=\"https:\/\/volteco.com\/wp-content\/uploads\/2025\/07\/07-1-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va\",\"name\":\"Impermeabilizzazione nuovo complesso industriale - Ispria - VA | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/07-1-2.jpg\",\"datePublished\":\"2025-07-17T12:27:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#primaryimage\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/07-1-2.jpg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/07-1-2.jpg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Impermeabilizzazione nuovo complesso industriale &#8211; Ispria &#8211; VA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impermeabilizzazione nuovo complesso industriale - Ispria - VA | Volteco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va","og_locale":"it_IT","og_type":"article","og_title":"Impermeabilizzazione nuovo complesso industriale - Ispria - VA | Volteco","og_description":"Lavori di impermeabilizzazione nuovo edificio industriale sito a Ispira in provincia di Varese.","og_url":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","og_image":[{"width":900,"height":675,"url":"https:\/\/volteco.com\/wp-content\/uploads\/2025\/07\/07-1-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va","url":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va","name":"Impermeabilizzazione nuovo complesso industriale - Ispria - VA | Volteco","isPartOf":{"@id":"https:\/\/volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#primaryimage"},"image":{"@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#primaryimage"},"thumbnailUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2025\/07\/07-1-2.jpg","datePublished":"2025-07-17T12:27:58+00:00","breadcrumb":{"@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#primaryimage","url":"https:\/\/volteco.com\/wp-content\/uploads\/2025\/07\/07-1-2.jpg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2025\/07\/07-1-2.jpg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-nuovo-complesso-industriale-ispria-va#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/volteco.com\/it"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/volteco.com\/it\/referenze"},{"@type":"ListItem","position":3,"name":"Impermeabilizzazione nuovo complesso industriale &#8211; Ispria &#8211; VA"}]},{"@type":"WebSite","@id":"https:\/\/volteco.com\/it\/#website","url":"https:\/\/volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference\/64828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media\/64848"}],"wp:attachment":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media?parent=64828"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/scope?post=64828"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/problem?post=64828"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/country?post=64828"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/building?post=64828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}