{"id":70636,"date":"2026-03-12T08:04:28","date_gmt":"2026-03-12T08:04:28","guid":{"rendered":"https:\/\/volteco.com\/?post_type=reference&#038;p=70636"},"modified":"2026-03-12T08:35:49","modified_gmt":"2026-03-12T08:35:49","slug":"impermeabilizzazione-piscina-privata-pai-vr","status":"publish","type":"reference","link":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr","title":{"rendered":"Impermeabilizzazione piscina privata &#8211; Pai &#8211; VR"},"content":{"rendered":"<p>Lavori di impermeabilizzazione di piscina privata sito a Pai in provincia di Verona.<\/p>\n","protected":false},"featured_media":70656,"template":"","scope":[1116],"problem":[922,748,918,920,921,1139,1138,1129,1126,1132],"country":[1196],"building":[35],"class_list":["post-70636","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-piscine-e-vasche","problem-infiltrazioni-soluzioni","problem-fessurazioni-soluzioni","problem-muffe-soluzioni","problem-indebolimento-soluzioni","problem-deterioramento-soluzioni","problem-efflorescenze-muffe-alghe-e-funghi","problem-c-a-degradato","problem-indebolimento-della-struttura","problem-tubi-non-sigillati","problem-efflorescenze-su-piastrella","country-veneto","building-residenziale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impermeabilizzazione piscina privata - Pai - VR | Volteco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impermeabilizzazione piscina privata - Pai - VR | Volteco\" \/>\n<meta property=\"og:description\" content=\"Lavori di impermeabilizzazione di piscina privata sito a Pai in provincia di Verona.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T08:35:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/volteco.com\/wp-content\/uploads\/2026\/03\/08-1-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-piscina-privata-pai-vr\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-piscina-privata-pai-vr\",\"name\":\"Impermeabilizzazione piscina privata - Pai - VR | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-piscina-privata-pai-vr#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-piscina-privata-pai-vr#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/08-1-5.jpg\",\"datePublished\":\"2026-03-12T08:04:28+00:00\",\"dateModified\":\"2026-03-12T08:35:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-piscina-privata-pai-vr#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-piscina-privata-pai-vr\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-piscina-privata-pai-vr#primaryimage\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/08-1-5.jpg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/08-1-5.jpg\",\"width\":900,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-piscina-privata-pai-vr#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Impermeabilizzazione piscina privata &#8211; Pai &#8211; VR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impermeabilizzazione piscina privata - Pai - VR | Volteco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr","og_locale":"it_IT","og_type":"article","og_title":"Impermeabilizzazione piscina privata - Pai - VR | Volteco","og_description":"Lavori di impermeabilizzazione di piscina privata sito a Pai in provincia di Verona.","og_url":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2026-03-12T08:35:49+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/volteco.com\/wp-content\/uploads\/2026\/03\/08-1-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr","url":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr","name":"Impermeabilizzazione piscina privata - Pai - VR | Volteco","isPartOf":{"@id":"https:\/\/volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr#primaryimage"},"image":{"@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr#primaryimage"},"thumbnailUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2026\/03\/08-1-5.jpg","datePublished":"2026-03-12T08:04:28+00:00","dateModified":"2026-03-12T08:35:49+00:00","breadcrumb":{"@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr#primaryimage","url":"https:\/\/volteco.com\/wp-content\/uploads\/2026\/03\/08-1-5.jpg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2026\/03\/08-1-5.jpg","width":900,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-piscina-privata-pai-vr#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/volteco.com\/it"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/volteco.com\/it\/referenze"},{"@type":"ListItem","position":3,"name":"Impermeabilizzazione piscina privata &#8211; Pai &#8211; VR"}]},{"@type":"WebSite","@id":"https:\/\/volteco.com\/it\/#website","url":"https:\/\/volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference\/70636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media\/70656"}],"wp:attachment":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media?parent=70636"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/scope?post=70636"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/problem?post=70636"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/country?post=70636"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/building?post=70636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}