{"id":7682,"date":"2021-10-22T09:56:26","date_gmt":"2021-10-22T09:56:26","guid":{"rendered":"https:\/\/volteco.com\/reference\/rifacimento-facciata-condominio-montegranaro-mc\/"},"modified":"2022-09-12T09:14:20","modified_gmt":"2022-09-12T09:14:20","slug":"rifacimento-facciata-condominio-montegranaro-mc","status":"publish","type":"reference","link":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc","title":{"rendered":"Rifacimento facciata condominio &#8211; Montegranaro &#8211; MC"},"content":{"rendered":"","protected":false},"featured_media":12823,"template":"","scope":[1120],"problem":[918,1139],"country":[1195,1213],"building":[35],"class_list":["post-7682","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-ripristino-e-protezione-facciate","problem-muffe-soluzioni","problem-efflorescenze-muffe-alghe-e-funghi","country-italia","country-marche","building-residenziale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rifacimento facciata condominio, Montegranaro, MC | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata condominio, Montegranaro, MC.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rifacimento facciata condominio, Montegranaro, MC | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata condominio, Montegranaro, MC.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-12T09:14:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/11_5-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"808\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-condominio-montegranaro-mc\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-condominio-montegranaro-mc\",\"name\":\"Rifacimento facciata condominio, Montegranaro, MC | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-condominio-montegranaro-mc#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-condominio-montegranaro-mc#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/11_5-1.jpg\",\"datePublished\":\"2021-10-22T09:56:26+00:00\",\"dateModified\":\"2022-09-12T09:14:20+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata condominio, Montegranaro, MC.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-condominio-montegranaro-mc#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-condominio-montegranaro-mc\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-condominio-montegranaro-mc#primaryimage\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/11_5-1.jpg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/11_5-1.jpg\",\"width\":768,\"height\":808},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/rifacimento-facciata-condominio-montegranaro-mc#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rifacimento facciata condominio &#8211; Montegranaro &#8211; MC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rifacimento facciata condominio, Montegranaro, MC | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata condominio, Montegranaro, MC.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc","og_locale":"it_IT","og_type":"article","og_title":"Rifacimento facciata condominio, Montegranaro, MC | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata condominio, Montegranaro, MC.","og_url":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2022-09-12T09:14:20+00:00","og_image":[{"width":768,"height":808,"url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/11_5-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc","url":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc","name":"Rifacimento facciata condominio, Montegranaro, MC | Volteco","isPartOf":{"@id":"https:\/\/volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc#primaryimage"},"image":{"@id":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc#primaryimage"},"thumbnailUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/11_5-1.jpg","datePublished":"2021-10-22T09:56:26+00:00","dateModified":"2022-09-12T09:14:20+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Rifacimento facciata condominio, Montegranaro, MC.","breadcrumb":{"@id":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc#primaryimage","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/11_5-1.jpg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/11_5-1.jpg","width":768,"height":808},{"@type":"BreadcrumbList","@id":"https:\/\/volteco.com\/it\/referenze\/rifacimento-facciata-condominio-montegranaro-mc#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/volteco.com\/it"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/volteco.com\/it\/referenze"},{"@type":"ListItem","position":3,"name":"Rifacimento facciata condominio &#8211; Montegranaro &#8211; MC"}]},{"@type":"WebSite","@id":"https:\/\/volteco.com\/it\/#website","url":"https:\/\/volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference\/7682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media\/12823"}],"wp:attachment":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media?parent=7682"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/scope?post=7682"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/problem?post=7682"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/country?post=7682"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/building?post=7682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}