{"id":8461,"date":"2021-10-22T10:00:37","date_gmt":"2021-10-22T10:00:37","guid":{"rendered":"https:\/\/volteco.com\/reference\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no\/"},"modified":"2025-11-26T11:58:00","modified_gmt":"2025-11-26T11:58:00","slug":"impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no","status":"publish","type":"reference","link":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no","title":{"rendered":"Impermeabilizzazione terrazzi e copertura piana villa &#8211; Auzate &#8211; Gozzano &#8211; NO"},"content":{"rendered":"","protected":false},"featured_media":14518,"template":"","scope":[1117],"problem":[922,748,1128,1132,1131],"country":[1195,1198],"building":[35],"class_list":["post-8461","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-impermeabilizzazione-terrazzi-e-balconi","problem-infiltrazioni-soluzioni","problem-fessurazioni-soluzioni","problem-infiltrazioni-dal-solaio","problem-efflorescenze-su-piastrella","problem-pavimenti-danneggiati-da-gelo-e-disgelo","country-italia","country-piemonte","building-residenziale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impermeabilizzazione terrazzi e copertura piana villa - Auzate - Gozzano - NO | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione terrazzi e copertura piana villa, Auzate, Gozzano, NO.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impermeabilizzazione terrazzi e copertura piana villa - Auzate - Gozzano - NO | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione terrazzi e copertura piana villa, Auzate, Gozzano, NO.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-26T11:58:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/12_12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no\",\"name\":\"Impermeabilizzazione terrazzi e copertura piana villa - Auzate - Gozzano - NO | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/12_12.jpg\",\"datePublished\":\"2021-10-22T10:00:37+00:00\",\"dateModified\":\"2025-11-26T11:58:00+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione terrazzi e copertura piana villa, Auzate, Gozzano, NO.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#primaryimage\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/12_12.jpg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/12_12.jpg\",\"width\":900,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Impermeabilizzazione terrazzi e copertura piana villa &#8211; Auzate &#8211; Gozzano &#8211; NO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impermeabilizzazione terrazzi e copertura piana villa - Auzate - Gozzano - NO | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione terrazzi e copertura piana villa, Auzate, Gozzano, NO.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no","og_locale":"it_IT","og_type":"article","og_title":"Impermeabilizzazione terrazzi e copertura piana villa - Auzate - Gozzano - NO | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione terrazzi e copertura piana villa, Auzate, Gozzano, NO.","og_url":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2025-11-26T11:58:00+00:00","og_image":[{"width":900,"height":540,"url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/12_12.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no","url":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no","name":"Impermeabilizzazione terrazzi e copertura piana villa - Auzate - Gozzano - NO | Volteco","isPartOf":{"@id":"https:\/\/volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#primaryimage"},"image":{"@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#primaryimage"},"thumbnailUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/12_12.jpg","datePublished":"2021-10-22T10:00:37+00:00","dateModified":"2025-11-26T11:58:00+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Impermeabilizzazione terrazzi e copertura piana villa, Auzate, Gozzano, NO.","breadcrumb":{"@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#primaryimage","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/12_12.jpg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/12_12.jpg","width":900,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/volteco.com\/it\/referenze\/impermeabilizzazione-terrazzi-e-copertura-piana-villa-auzate-gozzano-no#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/volteco.com\/it"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/volteco.com\/it\/referenze"},{"@type":"ListItem","position":3,"name":"Impermeabilizzazione terrazzi e copertura piana villa &#8211; Auzate &#8211; Gozzano &#8211; NO"}]},{"@type":"WebSite","@id":"https:\/\/volteco.com\/it\/#website","url":"https:\/\/volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference\/8461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media\/14518"}],"wp:attachment":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media?parent=8461"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/scope?post=8461"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/problem?post=8461"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/country?post=8461"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/building?post=8461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}