{"id":9697,"date":"2021-10-22T10:07:18","date_gmt":"2021-10-22T10:07:18","guid":{"rendered":"https:\/\/volteco.com\/reference\/risanamento-deposito-farmaceutico-cagliari-ca\/"},"modified":"2025-04-23T12:59:58","modified_gmt":"2025-04-23T12:59:58","slug":"risanamento-deposito-farmaceutico-cagliari-ca","status":"publish","type":"reference","link":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca","title":{"rendered":"Risanamento deposito farmaceutico &#8211; Cagliari &#8211; CA"},"content":{"rendered":"","protected":false},"featured_media":15285,"template":"","scope":[1119],"problem":[923,921,1137,1247],"country":[1195,1207],"building":[1038],"class_list":["post-9697","reference","type-reference","status-publish","has-post-thumbnail","hentry","scope-risanamento-umidita-murature","problem-umidita-di-risalita-soluzioni","problem-deterioramento-soluzioni","problem-deterioramento-delle-murature","problem-umidita-di-risalita","country-italia","country-sardegna","building-commerciale"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risanamento deposito farmaceutico - Cagliari - CA | Volteco<\/title>\n<meta name=\"description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento deposito farmaceutico, Cagliari, CA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risanamento deposito farmaceutico - Cagliari - CA | Volteco\" \/>\n<meta property=\"og:description\" content=\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento deposito farmaceutico, Cagliari, CA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca\" \/>\n<meta property=\"og:site_name\" content=\"Volteco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VoltecoSpa\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T12:59:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/deposito-ca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/risanamento-deposito-farmaceutico-cagliari-ca\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/risanamento-deposito-farmaceutico-cagliari-ca\",\"name\":\"Risanamento deposito farmaceutico - Cagliari - CA | Volteco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/risanamento-deposito-farmaceutico-cagliari-ca#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/risanamento-deposito-farmaceutico-cagliari-ca#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/deposito-ca.jpg\",\"datePublished\":\"2021-10-22T10:07:18+00:00\",\"dateModified\":\"2025-04-23T12:59:58+00:00\",\"description\":\"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento deposito farmaceutico, Cagliari, CA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/risanamento-deposito-farmaceutico-cagliari-ca#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/risanamento-deposito-farmaceutico-cagliari-ca\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/risanamento-deposito-farmaceutico-cagliari-ca#primaryimage\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/deposito-ca.jpg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/deposito-ca.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\\\/risanamento-deposito-farmaceutico-cagliari-ca#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referenze\",\"item\":\"https:\\\/\\\/volteco.com\\\/it\\\/referenze\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Risanamento deposito farmaceutico &#8211; Cagliari &#8211; CA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"name\":\"Volteco\",\"description\":\"Prodotti impermeabilizzanti\",\"publisher\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/volteco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#organization\",\"name\":\"Volteco S.p.A.\",\"url\":\"https:\\\/\\\/volteco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"contentUrl\":\"https:\\\/\\\/volteco.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Logo-color@2x.svg\",\"width\":180,\"height\":54,\"caption\":\"Volteco S.p.A.\"},\"image\":{\"@id\":\"https:\\\/\\\/volteco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VoltecoSpa\",\"https:\\\/\\\/www.instagram.com\\\/voltecospa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/volteco-spa\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/Voltecospa\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risanamento deposito farmaceutico - Cagliari - CA | Volteco","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento deposito farmaceutico, Cagliari, CA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca","og_locale":"it_IT","og_type":"article","og_title":"Risanamento deposito farmaceutico - Cagliari - CA | Volteco","og_description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento deposito farmaceutico, Cagliari, CA.","og_url":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca","og_site_name":"Volteco","article_publisher":"https:\/\/www.facebook.com\/VoltecoSpa","article_modified_time":"2025-04-23T12:59:58+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/deposito-ca.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca","url":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca","name":"Risanamento deposito farmaceutico - Cagliari - CA | Volteco","isPartOf":{"@id":"https:\/\/volteco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca#primaryimage"},"image":{"@id":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca#primaryimage"},"thumbnailUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/deposito-ca.jpg","datePublished":"2021-10-22T10:07:18+00:00","dateModified":"2025-04-23T12:59:58+00:00","description":"Entra nel sito e scopri le nostre referenze: clicca qui per vedere le lavorazioni fatte per Risanamento deposito farmaceutico, Cagliari, CA.","breadcrumb":{"@id":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca#primaryimage","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/deposito-ca.jpg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/11\/deposito-ca.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/volteco.com\/it\/referenze\/risanamento-deposito-farmaceutico-cagliari-ca#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/volteco.com\/it"},{"@type":"ListItem","position":2,"name":"Referenze","item":"https:\/\/volteco.com\/it\/referenze"},{"@type":"ListItem","position":3,"name":"Risanamento deposito farmaceutico &#8211; Cagliari &#8211; CA"}]},{"@type":"WebSite","@id":"https:\/\/volteco.com\/it\/#website","url":"https:\/\/volteco.com\/it\/","name":"Volteco","description":"Prodotti impermeabilizzanti","publisher":{"@id":"https:\/\/volteco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/volteco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/volteco.com\/it\/#organization","name":"Volteco S.p.A.","url":"https:\/\/volteco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","contentUrl":"https:\/\/volteco.com\/wp-content\/uploads\/2021\/09\/Logo-color@2x.svg","width":180,"height":54,"caption":"Volteco S.p.A."},"image":{"@id":"https:\/\/volteco.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VoltecoSpa","https:\/\/www.instagram.com\/voltecospa\/","https:\/\/www.linkedin.com\/company\/volteco-spa","https:\/\/www.youtube.com\/user\/Voltecospa"]}]}},"_links":{"self":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference\/9697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/reference"}],"about":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/types\/reference"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media\/15285"}],"wp:attachment":[{"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/media?parent=9697"}],"wp:term":[{"taxonomy":"scope","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/scope?post=9697"},{"taxonomy":"problem","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/problem?post=9697"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/country?post=9697"},{"taxonomy":"building","embeddable":true,"href":"https:\/\/volteco.com\/it\/wp-json\/wp\/v2\/building?post=9697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}